{"id":9991,"date":"2022-01-03T09:31:06","date_gmt":"2022-01-03T09:31:06","guid":{"rendered":"https:\/\/careers.expleo.com\/global\/en\/?post_type=employee-stories&#038;p=15777"},"modified":"2025-04-28T06:40:53","modified_gmt":"2025-04-28T06:40:53","slug":"laura","status":"publish","type":"life-at-expleo","link":"https:\/\/careers.expleo.com\/fr\/life-at-expleo\/laura\/","title":{"rendered":"Laura"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"9991\" class=\"elementor elementor-9991\" data-elementor-post-type=\"life-at-expleo\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7ff1075 gg-title-desc-list gg-class-for-iphone8 gg-article-content gg-employee-story-template elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7ff1075\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ae9191b gg-tablet-view\" data-id=\"ae9191b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0fa6c1b gg-font-v14 elementor-widget elementor-widget-heading\" data-id=\"0fa6c1b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">UNE JOURN\u00c9E TYPE AU TRAVAIL<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a2d9ae0 gg-font-v9 elementor-widget elementor-widget-text-editor\" data-id=\"a2d9ae0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>Echanger avec diff\u00e9rentes personnes du secteur<\/li><li>Collecter des informations<\/li><li>Analyser et pr\u00e9senter ces informations de mani\u00e8re pertinente<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6ef8f5d gg-title-with-scrolled-description gg-container-small-ptb-96 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6ef8f5d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-887cc87\" data-id=\"887cc87\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-48523d5 gg-tagline-heading-left elementor-widget elementor-widget-text-editor\" data-id=\"48523d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>3 questions en bref<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-846c708 scrollable-column gg-vertical-counter-without-scroll\" data-id=\"846c708\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4938c90 elementor-widget elementor-widget-icon-box\" data-id=\"4938c90\" data-element_type=\"widget\" data-e-type=\"widget\" tabindex=\"0\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t#1<br>Qu'est-ce que tu aimes le plus dans ton travail de Business Analyst?\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t\u00c0 ce stade de ma carri\u00e8re, j'apprends \u00e0 accepter de ne pas me sentir toujours \u00e0 l'aise et \u00e0 \u00eatre challeng\u00e9e. C'est comme \u00e7a que je progresse le plus !\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-35fe4ff elementor-widget elementor-widget-icon-box\" data-id=\"35fe4ff\" data-element_type=\"widget\" data-e-type=\"widget\" tabindex=\"0\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t#2<br>Penses-tu qu'Expleo est un bon employeur ? Pourquoi ?\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tLe meilleur atout d'Expleo, c'est ses \u00e9quipes. En 6 ans, j'ai fait beaucoup de rencontres, beaucoup appris et re\u00e7u le soutien de mes coll\u00e8gues. Il y a aussi beaucoup d'opportunit\u00e9s d'\u00e9volution professionnelle chez Expleo, c'est tr\u00e8s motivant.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6ba6b57 elementor-widget elementor-widget-icon-box\" data-id=\"6ba6b57\" data-element_type=\"widget\" data-e-type=\"widget\" tabindex=\"0\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t#3<br>Quelle est ta plus grande fiert\u00e9 en tant que Business Analyst chez Expleo ?\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tJ'\u00e9tais tr\u00e8s fi\u00e8re quand j'ai eu les retours de mon premier client. Je me suis vraiment sentie \u00e0 la hauteur de mon poste et j'ai prouv\u00e9 que j'avais acquis les bonnes comp\u00e9tences. C'\u00e9tait aussi une grande source de motivation pour continuer \u00e0 progresser et \u00e0 donner le meilleur de moi-m\u00eame.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7362a61\" data-id=\"7362a61\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cdc2bf1 gg-outside-right-element elementor-widget elementor-widget-text-editor\" data-id=\"cdc2bf1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>D\u00c9ROULER<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6c50c60 gg-container-large gg-left-image-with-text-component-and-button elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6c50c60\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f1e3e08\" data-id=\"f1e3e08\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b751825 elementor-widget elementor-widget-image\" data-id=\"b751825\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1240\" height=\"868\" src=\"https:\/\/careers.expleo.com\/fr\/wp-content\/uploads\/2022\/04\/employer-branding-corner.jpg\" class=\"attachment-full size-full wp-image-18976\" alt=\"Employer Branding\" srcset=\"https:\/\/careers.expleo.com\/fr\/wp-content\/uploads\/2022\/04\/employer-branding-corner.jpg 1240w, https:\/\/careers.expleo.com\/fr\/wp-content\/uploads\/2022\/04\/employer-branding-corner-300x210.jpg 300w, https:\/\/careers.expleo.com\/fr\/wp-content\/uploads\/2022\/04\/employer-branding-corner-1024x717.jpg 1024w, https:\/\/careers.expleo.com\/fr\/wp-content\/uploads\/2022\/04\/employer-branding-corner-768x538.jpg 768w\" sizes=\"(max-width: 1240px) 100vw, 1240px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-73234e6 elementor-widget elementor-widget-gravity-advanced-cta\" data-id=\"73234e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"gravity-advanced-cta.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"gg-advanced-cta\">\r\n            \r\n        <h2 class=\"gg-advanced-cta__heading gg-font-v3\">\r\n                 Soyez vous-m\u00eame !                <\/h2>\r\n                <div class=\"gg-advanced-cta__description gg-font-v9\">\r\n            <span><p>Nous vous offrons un environnement inclusif et accessible, o\u00f9 tous les employ\u00e9s se sentent valoris\u00e9s et soutenus. Nous voulons que vous soyez la meilleure version de vous-m\u00eame et nous vous aiderons \u00e0 cr\u00e9er un lieu de travail qui refl\u00e8te la diversit\u00e9 des communaut\u00e9s dans lesquelles nous vivons et un environnement permettant de d\u00e9velopper votre potentiel.<\/p><\/span>        <\/div>\r\n        \r\n        <div class=\"gg-advanced-cta__button-first gg-advanced-cta__button gg-button-v4\">\r\n            <a href=\"https:\/\/careers.expleo.com\/fr\/notre-culture\/\">\r\n                EN SAVOIR PLUS SUR LA VIE CHEZ EXPLEO            <\/a>\r\n        <\/div>\r\n\r\n                <\/div>\r\n\r\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Business Analyst au Royaume-Uni<\/p>\n","protected":false},"featured_media":12490,"parent":0,"template":"","meta":{"_oasis_is_in_workflow":0,"_oasis_original":0,"_oasis_task_priority":"","footnotes":""},"profil":[387],"topic":[],"industry-taxonomy":[41,39,47,135],"content-type":[515],"country":[105],"service":[187],"role-family":[110],"class_list":["post-9991","life-at-expleo","type-life-at-expleo","status-publish","has-post-thumbnail","hentry","profil-graduate","industry-taxonomy-banking-and-financial-services","industry-taxonomy-energie-and-utilities","industry-taxonomy-public-sector","industry-taxonomy-sciences-de-la-vie","content-type-temoignages","country-royaume-uni","service-conseils-en-transformation","role-family-gestion-de-projet"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Expleo | Laura - Business Analyst<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez Laura, Business Analyst chez Expleo Royaume Uni et ses challenges aupr\u00e8s des diff\u00e9rents clients du groupe.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/careers.expleo.com\/fr\/life-at-expleo\/laura\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Laura\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez Laura, Business Analyst chez Expleo Royaume Uni et ses challenges aupr\u00e8s des diff\u00e9rents clients du groupe.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/careers.expleo.com\/fr\/life-at-expleo\/laura\/\" \/>\n<meta property=\"og:site_name\" content=\"FR\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-28T06:40:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/careers.expleo.com\/fr\/wp-content\/uploads\/2022\/01\/employee-stories-laura.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"740\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/careers.expleo.com\\\/fr\\\/life-at-expleo\\\/laura\\\/\",\"url\":\"https:\\\/\\\/careers.expleo.com\\\/fr\\\/life-at-expleo\\\/laura\\\/\",\"name\":\"Expleo | Laura - Business Analyst\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/careers.expleo.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/careers.expleo.com\\\/fr\\\/life-at-expleo\\\/laura\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/careers.expleo.com\\\/fr\\\/life-at-expleo\\\/laura\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/careers.expleo.com\\\/fr\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/employee-stories-laura.jpg\",\"datePublished\":\"2022-01-03T09:31:06+00:00\",\"dateModified\":\"2025-04-28T06:40:53+00:00\",\"description\":\"D\u00e9couvrez Laura, Business Analyst chez Expleo Royaume Uni et ses challenges aupr\u00e8s des diff\u00e9rents clients du groupe.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/careers.expleo.com\\\/fr\\\/life-at-expleo\\\/laura\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/careers.expleo.com\\\/fr\\\/life-at-expleo\\\/laura\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/careers.expleo.com\\\/fr\\\/life-at-expleo\\\/laura\\\/#primaryimage\",\"url\":\"https:\\\/\\\/careers.expleo.com\\\/fr\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/employee-stories-laura.jpg\",\"contentUrl\":\"https:\\\/\\\/careers.expleo.com\\\/fr\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/employee-stories-laura.jpg\",\"width\":740,\"height\":400,\"caption\":\"Young blond woman with straight hair is smiling\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/careers.expleo.com\\\/fr\\\/life-at-expleo\\\/laura\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/careers.expleo.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Life@Expleo\",\"item\":\"https:\\\/\\\/careers.expleo.com\\\/fr\\\/life-at-expleo\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Laura\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/careers.expleo.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/careers.expleo.com\\\/fr\\\/\",\"name\":\"EXPLEO | FR\",\"description\":\"Expleo\",\"publisher\":{\"@id\":\"https:\\\/\\\/careers.expleo.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/careers.expleo.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/careers.expleo.com\\\/fr\\\/#organization\",\"name\":\"EXPLEO | FR\",\"url\":\"https:\\\/\\\/careers.expleo.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/careers.expleo.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/careers.expleo.com\\\/fr\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/expleo-logo-and-tagline.png\",\"contentUrl\":\"https:\\\/\\\/careers.expleo.com\\\/fr\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/expleo-logo-and-tagline.png\",\"width\":1600,\"height\":774,\"caption\":\"EXPLEO | FR\"},\"image\":{\"@id\":\"https:\\\/\\\/careers.expleo.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Expleo | Laura - Business Analyst","description":"D\u00e9couvrez Laura, Business Analyst chez Expleo Royaume Uni et ses challenges aupr\u00e8s des diff\u00e9rents clients du groupe.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/careers.expleo.com\/fr\/life-at-expleo\/laura\/","og_locale":"fr_FR","og_type":"article","og_title":"Laura","og_description":"D\u00e9couvrez Laura, Business Analyst chez Expleo Royaume Uni et ses challenges aupr\u00e8s des diff\u00e9rents clients du groupe.","og_url":"https:\/\/careers.expleo.com\/fr\/life-at-expleo\/laura\/","og_site_name":"FR","article_modified_time":"2025-04-28T06:40:53+00:00","og_image":[{"width":740,"height":400,"url":"https:\/\/careers.expleo.com\/fr\/wp-content\/uploads\/2022\/01\/employee-stories-laura.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/careers.expleo.com\/fr\/life-at-expleo\/laura\/","url":"https:\/\/careers.expleo.com\/fr\/life-at-expleo\/laura\/","name":"Expleo | Laura - Business Analyst","isPartOf":{"@id":"https:\/\/careers.expleo.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/careers.expleo.com\/fr\/life-at-expleo\/laura\/#primaryimage"},"image":{"@id":"https:\/\/careers.expleo.com\/fr\/life-at-expleo\/laura\/#primaryimage"},"thumbnailUrl":"https:\/\/careers.expleo.com\/fr\/wp-content\/uploads\/2022\/01\/employee-stories-laura.jpg","datePublished":"2022-01-03T09:31:06+00:00","dateModified":"2025-04-28T06:40:53+00:00","description":"D\u00e9couvrez Laura, Business Analyst chez Expleo Royaume Uni et ses challenges aupr\u00e8s des diff\u00e9rents clients du groupe.","breadcrumb":{"@id":"https:\/\/careers.expleo.com\/fr\/life-at-expleo\/laura\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/careers.expleo.com\/fr\/life-at-expleo\/laura\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/careers.expleo.com\/fr\/life-at-expleo\/laura\/#primaryimage","url":"https:\/\/careers.expleo.com\/fr\/wp-content\/uploads\/2022\/01\/employee-stories-laura.jpg","contentUrl":"https:\/\/careers.expleo.com\/fr\/wp-content\/uploads\/2022\/01\/employee-stories-laura.jpg","width":740,"height":400,"caption":"Young blond woman with straight hair is smiling"},{"@type":"BreadcrumbList","@id":"https:\/\/careers.expleo.com\/fr\/life-at-expleo\/laura\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/careers.expleo.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Life@Expleo","item":"https:\/\/careers.expleo.com\/fr\/life-at-expleo\/"},{"@type":"ListItem","position":3,"name":"Laura"}]},{"@type":"WebSite","@id":"https:\/\/careers.expleo.com\/fr\/#website","url":"https:\/\/careers.expleo.com\/fr\/","name":"EXPLEO | FR","description":"Expleo","publisher":{"@id":"https:\/\/careers.expleo.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/careers.expleo.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/careers.expleo.com\/fr\/#organization","name":"EXPLEO | FR","url":"https:\/\/careers.expleo.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/careers.expleo.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/careers.expleo.com\/fr\/wp-content\/uploads\/2019\/02\/expleo-logo-and-tagline.png","contentUrl":"https:\/\/careers.expleo.com\/fr\/wp-content\/uploads\/2019\/02\/expleo-logo-and-tagline.png","width":1600,"height":774,"caption":"EXPLEO | FR"},"image":{"@id":"https:\/\/careers.expleo.com\/fr\/#\/schema\/logo\/image\/"}}]}},"hreflang":{"rendered":"<link rel=\"alternate\" href=\"https:\/\/careers.expleo.com\/en\/life-at-expleo\/laura\/\" hreflang=\"x-default\"\/>\n<link rel=\"alternate\" href=\"https:\/\/careers.expleo.com\/en\/life-at-expleo\/laura\/\" hreflang=\"en\"\/>\n<link rel=\"alternate\" href=\"https:\/\/careers.expleo.com\/fr\/life-at-expleo\/laura\/\" hreflang=\"fr\"\/>\n<link rel=\"alternate\" href=\"https:\/\/careers.expleo.com\/de\/life-at-expleo\/laura\/\" hreflang=\"de\"\/>\n","structure":[{"blogId":4,"blogIsHidden":false,"postId":15777,"url":"https:\/\/careers.expleo.com\/en\/life-at-expleo\/laura\/","language":"en","default":true},{"blogId":5,"blogIsHidden":false,"postId":9991,"url":"https:\/\/careers.expleo.com\/fr\/life-at-expleo\/laura\/","language":"fr","default":false},{"blogId":6,"blogIsHidden":false,"postId":10338,"url":"https:\/\/careers.expleo.com\/de\/life-at-expleo\/laura\/","language":"de","default":false}]},"_links":{"self":[{"href":"https:\/\/careers.expleo.com\/fr\/wp-json\/wp\/v2\/life-at-expleo\/9991","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/careers.expleo.com\/fr\/wp-json\/wp\/v2\/life-at-expleo"}],"about":[{"href":"https:\/\/careers.expleo.com\/fr\/wp-json\/wp\/v2\/types\/life-at-expleo"}],"version-history":[{"count":10,"href":"https:\/\/careers.expleo.com\/fr\/wp-json\/wp\/v2\/life-at-expleo\/9991\/revisions"}],"predecessor-version":[{"id":29064,"href":"https:\/\/careers.expleo.com\/fr\/wp-json\/wp\/v2\/life-at-expleo\/9991\/revisions\/29064"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/careers.expleo.com\/fr\/wp-json\/wp\/v2\/media\/12490"}],"wp:attachment":[{"href":"https:\/\/careers.expleo.com\/fr\/wp-json\/wp\/v2\/media?parent=9991"}],"wp:term":[{"taxonomy":"profil","embeddable":true,"href":"https:\/\/careers.expleo.com\/fr\/wp-json\/wp\/v2\/profil?post=9991"},{"taxonomy":"topic","embeddable":true,"href":"https:\/\/careers.expleo.com\/fr\/wp-json\/wp\/v2\/topic?post=9991"},{"taxonomy":"industry-taxonomy","embeddable":true,"href":"https:\/\/careers.expleo.com\/fr\/wp-json\/wp\/v2\/industry-taxonomy?post=9991"},{"taxonomy":"content-type","embeddable":true,"href":"https:\/\/careers.expleo.com\/fr\/wp-json\/wp\/v2\/content-type?post=9991"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/careers.expleo.com\/fr\/wp-json\/wp\/v2\/country?post=9991"},{"taxonomy":"service","embeddable":true,"href":"https:\/\/careers.expleo.com\/fr\/wp-json\/wp\/v2\/service?post=9991"},{"taxonomy":"role-family","embeddable":true,"href":"https:\/\/careers.expleo.com\/fr\/wp-json\/wp\/v2\/role-family?post=9991"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}