{"id":9928,"date":"2022-01-03T09:31:06","date_gmt":"2022-01-03T09:31:06","guid":{"rendered":"https:\/\/careers.expleo.com\/global\/en\/?post_type=employee-stories&#038;p=15705"},"modified":"2025-04-28T06:40:25","modified_gmt":"2025-04-28T06:40:25","slug":"lamiae","status":"publish","type":"life-at-expleo","link":"https:\/\/careers.expleo.com\/fr\/life-at-expleo\/lamiae\/","title":{"rendered":"Lamiae"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"9928\" class=\"elementor elementor-9928\" data-elementor-post-type=\"life-at-expleo\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e1fbe3b gg-title-with-scrolled-description gg-container-small-ptb-96 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e1fbe3b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-fc577af\" data-id=\"fc577af\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1223941 gg-tagline-heading-left elementor-widget elementor-widget-text-editor\" data-id=\"1223941\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>3 questions en bref<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-ff7b582 scrollable-column gg-vertical-counter-without-scroll\" data-id=\"ff7b582\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c9fef84 elementor-widget elementor-widget-icon-box\" data-id=\"c9fef84\" data-element_type=\"widget\" data-e-type=\"widget\" tabindex=\"0\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t#1<br>Qu'est-ce que tu aimes le plus dans ton travail en Data Science ?\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tSe r\u00e9unir avec les coll\u00e8gues, partager nos quotidiens, nos id\u00e9es, discuter des points bloquants. Cela nous permet d\u2019avancer ensemble et d\u2019avoir une belle ambiance.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ca7f61f elementor-widget elementor-widget-icon-box\" data-id=\"ca7f61f\" data-element_type=\"widget\" data-e-type=\"widget\" tabindex=\"0\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t#2<br>Comment Expleo a pu t'aider \u00e0 progresser ?\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tJe suis dipl\u00f4m\u00e9e du d\u00e9partement math\u00e9matique de l\u2019INSA de Rennes, j\u2019ai int\u00e9gr\u00e9 Expleo pour r\u00e9aliser mon stage de fin d\u2019\u00e9tudes pour ensuite y travailler en tant que Data Scientist. Et aujourd\u2019hui je suis Team Leader d\u2019une \u00e9quipe sp\u00e9cialis\u00e9e en Data.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-00399a4 elementor-widget elementor-widget-icon-box\" data-id=\"00399a4\" data-element_type=\"widget\" data-e-type=\"widget\" tabindex=\"0\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t#3<br>Penses-tu qu'Expleo est un bon employeur ? Pourquoi ?\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tL\u2019esprit de collaboration et de travail en \u00e9quipe est pr\u00e9dominant et surtout tr\u00e8s motivant. Les challenges et la diversit\u00e9 des sujets \u00e0 traiter sont pr\u00e9sents, on ne s\u2019ennuie jamais !\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-62d7bcc\" data-id=\"62d7bcc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-af0c009 gg-outside-right-element elementor-widget elementor-widget-text-editor\" data-id=\"af0c009\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>D\u00c9ROULER<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5a7e47f gg-container-large gg-left-image-with-text-component-and-button elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5a7e47f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-aaeaacf\" data-id=\"aaeaacf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-86eef6e elementor-widget elementor-widget-image\" data-id=\"86eef6e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1240\" height=\"868\" src=\"https:\/\/careers.expleo.com\/fr\/wp-content\/uploads\/2022\/04\/employer-branding-corner.jpg\" class=\"attachment-full size-full wp-image-18976\" alt=\"Employer Branding\" srcset=\"https:\/\/careers.expleo.com\/fr\/wp-content\/uploads\/2022\/04\/employer-branding-corner.jpg 1240w, https:\/\/careers.expleo.com\/fr\/wp-content\/uploads\/2022\/04\/employer-branding-corner-300x210.jpg 300w, https:\/\/careers.expleo.com\/fr\/wp-content\/uploads\/2022\/04\/employer-branding-corner-1024x717.jpg 1024w, https:\/\/careers.expleo.com\/fr\/wp-content\/uploads\/2022\/04\/employer-branding-corner-768x538.jpg 768w\" sizes=\"(max-width: 1240px) 100vw, 1240px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0752065 elementor-widget elementor-widget-gravity-advanced-cta\" data-id=\"0752065\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"gravity-advanced-cta.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"gg-advanced-cta\">\r\n            \r\n        <h2 class=\"gg-advanced-cta__heading gg-font-v3\">\r\n                 Soyez vous-m\u00eame !                <\/h2>\r\n                <div class=\"gg-advanced-cta__description gg-font-v9\">\r\n            <span><p>Nous vous offrons un environnement inclusif et accessible, o\u00f9 tous les employ\u00e9s se sentent valoris\u00e9s et soutenus. Nous voulons que vous soyez la meilleure version de vous-m\u00eame et nous vous aiderons \u00e0 cr\u00e9er un lieu de travail qui refl\u00e8te la diversit\u00e9 des communaut\u00e9s dans lesquelles nous vivons et un environnement permettant de d\u00e9velopper votre potentiel.<\/p><\/span>        <\/div>\r\n        \r\n        <div class=\"gg-advanced-cta__button-first gg-advanced-cta__button gg-button-v4\">\r\n            <a href=\"https:\/\/careers.expleo.com\/fr\/notre-culture\/\">\r\n                EN SAVOIR PLUS SUR LA VIE CHEZ EXPLEO            <\/a>\r\n        <\/div>\r\n\r\n                <\/div>\r\n\r\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Data Scientist en France<\/p>\n","protected":false},"featured_media":12487,"parent":0,"template":"","meta":{"_oasis_is_in_workflow":0,"_oasis_original":0,"_oasis_task_priority":"","footnotes":""},"profil":[387,389],"topic":[],"industry-taxonomy":[24],"content-type":[515],"country":[91],"service":[52,186],"role-family":[111],"class_list":["post-9928","life-at-expleo","type-life-at-expleo","status-publish","has-post-thumbnail","hentry","profil-graduate","profil-professionnel-experimente","industry-taxonomy-automobile","content-type-temoignages","country-france","service-big-data-analyse-de-donnees-ia-et-algorithmes-avances","service-gestion-de-linnovation-and-solutions","role-family-developpement-et-digital"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Expleo | Lamiae - Data Scientist<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez le m\u00e9tier de Lamiae chez Expleo, comme Data scientist et ses challenges aupr\u00e8s des diff\u00e9rents clients du groupe.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/careers.expleo.com\/fr\/life-at-expleo\/lamiae\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lamiae\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez le m\u00e9tier de Lamiae chez Expleo, comme Data scientist et ses challenges aupr\u00e8s des diff\u00e9rents clients du groupe.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/careers.expleo.com\/fr\/life-at-expleo\/lamiae\/\" \/>\n<meta property=\"og:site_name\" content=\"FR\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-28T06:40:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/careers.expleo.com\/fr\/wp-content\/uploads\/2022\/01\/employee-stories-lamiae.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"740\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/careers.expleo.com\\\/fr\\\/life-at-expleo\\\/lamiae\\\/\",\"url\":\"https:\\\/\\\/careers.expleo.com\\\/fr\\\/life-at-expleo\\\/lamiae\\\/\",\"name\":\"Expleo | Lamiae - Data Scientist\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/careers.expleo.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/careers.expleo.com\\\/fr\\\/life-at-expleo\\\/lamiae\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/careers.expleo.com\\\/fr\\\/life-at-expleo\\\/lamiae\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/careers.expleo.com\\\/fr\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/employee-stories-lamiae.jpg\",\"datePublished\":\"2022-01-03T09:31:06+00:00\",\"dateModified\":\"2025-04-28T06:40:25+00:00\",\"description\":\"D\u00e9couvrez le m\u00e9tier de Lamiae chez Expleo, comme Data scientist et ses challenges aupr\u00e8s des diff\u00e9rents clients du groupe.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/careers.expleo.com\\\/fr\\\/life-at-expleo\\\/lamiae\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/careers.expleo.com\\\/fr\\\/life-at-expleo\\\/lamiae\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/careers.expleo.com\\\/fr\\\/life-at-expleo\\\/lamiae\\\/#primaryimage\",\"url\":\"https:\\\/\\\/careers.expleo.com\\\/fr\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/employee-stories-lamiae.jpg\",\"contentUrl\":\"https:\\\/\\\/careers.expleo.com\\\/fr\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/employee-stories-lamiae.jpg\",\"width\":740,\"height\":400,\"caption\":\"Young woman with dark straight hair is smiling\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/careers.expleo.com\\\/fr\\\/life-at-expleo\\\/lamiae\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/careers.expleo.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Life@Expleo\",\"item\":\"https:\\\/\\\/careers.expleo.com\\\/fr\\\/life-at-expleo\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Lamiae\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/careers.expleo.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/careers.expleo.com\\\/fr\\\/\",\"name\":\"EXPLEO | FR\",\"description\":\"Expleo\",\"publisher\":{\"@id\":\"https:\\\/\\\/careers.expleo.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/careers.expleo.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/careers.expleo.com\\\/fr\\\/#organization\",\"name\":\"EXPLEO | FR\",\"url\":\"https:\\\/\\\/careers.expleo.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/careers.expleo.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/careers.expleo.com\\\/fr\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/expleo-logo-and-tagline.png\",\"contentUrl\":\"https:\\\/\\\/careers.expleo.com\\\/fr\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/expleo-logo-and-tagline.png\",\"width\":1600,\"height\":774,\"caption\":\"EXPLEO | FR\"},\"image\":{\"@id\":\"https:\\\/\\\/careers.expleo.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Expleo | Lamiae - Data Scientist","description":"D\u00e9couvrez le m\u00e9tier de Lamiae chez Expleo, comme Data scientist et ses challenges aupr\u00e8s des diff\u00e9rents clients du groupe.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/careers.expleo.com\/fr\/life-at-expleo\/lamiae\/","og_locale":"fr_FR","og_type":"article","og_title":"Lamiae","og_description":"D\u00e9couvrez le m\u00e9tier de Lamiae chez Expleo, comme Data scientist et ses challenges aupr\u00e8s des diff\u00e9rents clients du groupe.","og_url":"https:\/\/careers.expleo.com\/fr\/life-at-expleo\/lamiae\/","og_site_name":"FR","article_modified_time":"2025-04-28T06:40:25+00:00","og_image":[{"width":740,"height":400,"url":"https:\/\/careers.expleo.com\/fr\/wp-content\/uploads\/2022\/01\/employee-stories-lamiae.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/careers.expleo.com\/fr\/life-at-expleo\/lamiae\/","url":"https:\/\/careers.expleo.com\/fr\/life-at-expleo\/lamiae\/","name":"Expleo | Lamiae - Data Scientist","isPartOf":{"@id":"https:\/\/careers.expleo.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/careers.expleo.com\/fr\/life-at-expleo\/lamiae\/#primaryimage"},"image":{"@id":"https:\/\/careers.expleo.com\/fr\/life-at-expleo\/lamiae\/#primaryimage"},"thumbnailUrl":"https:\/\/careers.expleo.com\/fr\/wp-content\/uploads\/2022\/01\/employee-stories-lamiae.jpg","datePublished":"2022-01-03T09:31:06+00:00","dateModified":"2025-04-28T06:40:25+00:00","description":"D\u00e9couvrez le m\u00e9tier de Lamiae chez Expleo, comme Data scientist et ses challenges aupr\u00e8s des diff\u00e9rents clients du groupe.","breadcrumb":{"@id":"https:\/\/careers.expleo.com\/fr\/life-at-expleo\/lamiae\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/careers.expleo.com\/fr\/life-at-expleo\/lamiae\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/careers.expleo.com\/fr\/life-at-expleo\/lamiae\/#primaryimage","url":"https:\/\/careers.expleo.com\/fr\/wp-content\/uploads\/2022\/01\/employee-stories-lamiae.jpg","contentUrl":"https:\/\/careers.expleo.com\/fr\/wp-content\/uploads\/2022\/01\/employee-stories-lamiae.jpg","width":740,"height":400,"caption":"Young woman with dark straight hair is smiling"},{"@type":"BreadcrumbList","@id":"https:\/\/careers.expleo.com\/fr\/life-at-expleo\/lamiae\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/careers.expleo.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Life@Expleo","item":"https:\/\/careers.expleo.com\/fr\/life-at-expleo\/"},{"@type":"ListItem","position":3,"name":"Lamiae"}]},{"@type":"WebSite","@id":"https:\/\/careers.expleo.com\/fr\/#website","url":"https:\/\/careers.expleo.com\/fr\/","name":"EXPLEO | FR","description":"Expleo","publisher":{"@id":"https:\/\/careers.expleo.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/careers.expleo.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/careers.expleo.com\/fr\/#organization","name":"EXPLEO | FR","url":"https:\/\/careers.expleo.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/careers.expleo.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/careers.expleo.com\/fr\/wp-content\/uploads\/2019\/02\/expleo-logo-and-tagline.png","contentUrl":"https:\/\/careers.expleo.com\/fr\/wp-content\/uploads\/2019\/02\/expleo-logo-and-tagline.png","width":1600,"height":774,"caption":"EXPLEO | FR"},"image":{"@id":"https:\/\/careers.expleo.com\/fr\/#\/schema\/logo\/image\/"}}]}},"hreflang":{"rendered":"<link rel=\"alternate\" href=\"https:\/\/careers.expleo.com\/en\/life-at-expleo\/lamiae\/\" hreflang=\"x-default\"\/>\n<link rel=\"alternate\" href=\"https:\/\/careers.expleo.com\/en\/life-at-expleo\/lamiae\/\" hreflang=\"en\"\/>\n<link rel=\"alternate\" href=\"https:\/\/careers.expleo.com\/fr\/life-at-expleo\/lamiae\/\" hreflang=\"fr\"\/>\n<link rel=\"alternate\" href=\"https:\/\/careers.expleo.com\/de\/life-at-expleo\/lamiae\/\" hreflang=\"de\"\/>\n","structure":[{"blogId":4,"blogIsHidden":false,"postId":15705,"url":"https:\/\/careers.expleo.com\/en\/life-at-expleo\/lamiae\/","language":"en","default":true},{"blogId":5,"blogIsHidden":false,"postId":9928,"url":"https:\/\/careers.expleo.com\/fr\/life-at-expleo\/lamiae\/","language":"fr","default":false},{"blogId":6,"blogIsHidden":false,"postId":10284,"url":"https:\/\/careers.expleo.com\/de\/life-at-expleo\/lamiae\/","language":"de","default":false}]},"_links":{"self":[{"href":"https:\/\/careers.expleo.com\/fr\/wp-json\/wp\/v2\/life-at-expleo\/9928","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/careers.expleo.com\/fr\/wp-json\/wp\/v2\/life-at-expleo"}],"about":[{"href":"https:\/\/careers.expleo.com\/fr\/wp-json\/wp\/v2\/types\/life-at-expleo"}],"version-history":[{"count":10,"href":"https:\/\/careers.expleo.com\/fr\/wp-json\/wp\/v2\/life-at-expleo\/9928\/revisions"}],"predecessor-version":[{"id":29073,"href":"https:\/\/careers.expleo.com\/fr\/wp-json\/wp\/v2\/life-at-expleo\/9928\/revisions\/29073"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/careers.expleo.com\/fr\/wp-json\/wp\/v2\/media\/12487"}],"wp:attachment":[{"href":"https:\/\/careers.expleo.com\/fr\/wp-json\/wp\/v2\/media?parent=9928"}],"wp:term":[{"taxonomy":"profil","embeddable":true,"href":"https:\/\/careers.expleo.com\/fr\/wp-json\/wp\/v2\/profil?post=9928"},{"taxonomy":"topic","embeddable":true,"href":"https:\/\/careers.expleo.com\/fr\/wp-json\/wp\/v2\/topic?post=9928"},{"taxonomy":"industry-taxonomy","embeddable":true,"href":"https:\/\/careers.expleo.com\/fr\/wp-json\/wp\/v2\/industry-taxonomy?post=9928"},{"taxonomy":"content-type","embeddable":true,"href":"https:\/\/careers.expleo.com\/fr\/wp-json\/wp\/v2\/content-type?post=9928"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/careers.expleo.com\/fr\/wp-json\/wp\/v2\/country?post=9928"},{"taxonomy":"service","embeddable":true,"href":"https:\/\/careers.expleo.com\/fr\/wp-json\/wp\/v2\/service?post=9928"},{"taxonomy":"role-family","embeddable":true,"href":"https:\/\/careers.expleo.com\/fr\/wp-json\/wp\/v2\/role-family?post=9928"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}